{"id":1932,"date":"2025-05-06T17:59:56","date_gmt":"2025-05-06T17:59:56","guid":{"rendered":"https:\/\/archespace.org\/2025\/?post_type=cpt_finalizados&#038;p=1932"},"modified":"2025-05-09T11:15:40","modified_gmt":"2025-05-09T11:15:40","slug":"silvia","status":"publish","type":"cpt_finalizados","link":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/","title":{"rendered":"S\u00edlvia"},"featured_media":1933,"template":"","class_list":["post-1932","cpt_finalizados","type-cpt_finalizados","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edlvia - Arche 2025<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edlvia - Arche 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/\" \/>\n<meta property=\"og:site_name\" content=\"Arche 2025\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T11:15:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2025\/05\/silvia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/\",\"url\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/\",\"name\":\"S\u00edlvia - Arche 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/archespace.org\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/silvia.jpg\",\"datePublished\":\"2025-05-06T17:59:56+00:00\",\"dateModified\":\"2025-05-09T11:15:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/archespace.org\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/silvia.jpg\",\"contentUrl\":\"https:\\\/\\\/archespace.org\\\/2025\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/silvia.jpg\",\"width\":500,\"height\":400,\"caption\":\"Silvia_Esteve\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/filmes-finalizados\\\/silvia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/archespace.org\\\/2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edlvia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#website\",\"url\":\"https:\\\/\\\/archespace.org\\\/2025\\\/\",\"name\":\"Arche 2025\",\"description\":\"Espa\u00e7o de desenvolvimento e pensamento criativo\",\"publisher\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/archespace.org\\\/2025\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#organization\",\"name\":\"Arch\u00e9 2024\",\"url\":\"https:\\\/\\\/archespace.org\\\/2025\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/archespace.org\\\/2025\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ache-2024.png\",\"contentUrl\":\"https:\\\/\\\/archespace.org\\\/2025\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/ache-2024.png\",\"width\":2400,\"height\":1260,\"caption\":\"Arch\u00e9 2024\"},\"image\":{\"@id\":\"https:\\\/\\\/archespace.org\\\/2025\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edlvia - Arche 2025","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"S\u00edlvia - Arche 2025","og_url":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/","og_site_name":"Arche 2025","article_modified_time":"2025-05-09T11:15:40+00:00","og_image":[{"width":500,"height":400,"url":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2025\/05\/silvia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/","url":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/","name":"S\u00edlvia - Arche 2025","isPartOf":{"@id":"https:\/\/archespace.org\/2025\/#website"},"primaryImageOfPage":{"@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/#primaryimage"},"image":{"@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/#primaryimage"},"thumbnailUrl":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2025\/05\/silvia.jpg","datePublished":"2025-05-06T17:59:56+00:00","dateModified":"2025-05-09T11:15:40+00:00","breadcrumb":{"@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/#primaryimage","url":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2025\/05\/silvia.jpg","contentUrl":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2025\/05\/silvia.jpg","width":500,"height":400,"caption":"Silvia_Esteve"},{"@type":"BreadcrumbList","@id":"https:\/\/archespace.org\/2025\/filmes-finalizados\/silvia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/archespace.org\/2025\/"},{"@type":"ListItem","position":2,"name":"S\u00edlvia"}]},{"@type":"WebSite","@id":"https:\/\/archespace.org\/2025\/#website","url":"https:\/\/archespace.org\/2025\/","name":"Arche 2025","description":"Espa\u00e7o de desenvolvimento e pensamento criativo","publisher":{"@id":"https:\/\/archespace.org\/2025\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/archespace.org\/2025\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/archespace.org\/2025\/#organization","name":"Arch\u00e9 2024","url":"https:\/\/archespace.org\/2025\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/archespace.org\/2025\/#\/schema\/logo\/image\/","url":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2024\/03\/ache-2024.png","contentUrl":"https:\/\/archespace.org\/2025\/wp-content\/uploads\/2024\/03\/ache-2024.png","width":2400,"height":1260,"caption":"Arch\u00e9 2024"},"image":{"@id":"https:\/\/archespace.org\/2025\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/archespace.org\/2025\/wp-json\/wp\/v2\/cpt_finalizados\/1932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archespace.org\/2025\/wp-json\/wp\/v2\/cpt_finalizados"}],"about":[{"href":"https:\/\/archespace.org\/2025\/wp-json\/wp\/v2\/types\/cpt_finalizados"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archespace.org\/2025\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/archespace.org\/2025\/wp-json\/wp\/v2\/media?parent=1932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}